{"id":698,"date":"2018-04-05T07:27:23","date_gmt":"2018-04-05T07:27:23","guid":{"rendered":"http:\/\/allston.elated-themes.com\/?page_id=698"},"modified":"2021-03-05T00:39:13","modified_gmt":"2021-03-05T00:39:13","slug":"contact","status":"publish","type":"page","link":"https:\/\/espacio.co.cr\/rudinarquitectura\/en\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css=\u00bb.vc_custom_1525773762316{padding-top: 0px !important;}\u00bb parallax_background_image=\u00bb4338&#8243;][vc_column]<div class=\"eltdf-elements-holder   eltdf-one-column  eltdf-responsive-mode-768 \" ><div class=\"eltdf-eh-item lazyload\" style=\"background-image:inherit\" data-item-class=\"eltdf-eh-custom-5255\" data-1366-1600=\"281px 0 207px 0\" data-1024-1366=\"228px 0 152px\" data-bg-image=\"url(https:\/\/espacio.co.cr\/rudinarquitectura\/en\/wp-content\/uploads\/2018\/06\/casa_naranjo-33.jpg)\">\n\t\t<div class=\"eltdf-eh-item-inner\">\n\t\t<div class=\"eltdf-eh-item-content eltdf-eh-custom-5255\" style=\"padding: 300px 0 227px 0\">\n\t\t\t<h2 class=\"eltdf-custom-font-holder  eltdf-cf-6831  \" style=\"font-family: Open Sans;font-size: 90px;letter-spacing: 0.22em;text-transform: uppercase;text-align: center;color: #ffffff\" data-item-class=\"eltdf-cf-6831\" data-font-size-680=\"60px\">\n\tLet's start your project!<\/h2>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n<\/div>[\/vc_column][\/vc_row][vc_row equal_height=\u00bbyes\u00bb row_content_width=\u00bbgrid\u00bb disable_background_image=\u00bb\u00bb simple_background_image=\u00bb528&#8243; css=\u00bb.vc_custom_1591904707006{padding-right: 0px !important;padding-bottom: 133px !important;padding-left: 0px !important;}\u00bb][vc_column]<div class=\"eltdf-elements-holder   eltdf-one-column  eltdf-responsive-mode-1024 \" ><div class=\"eltdf-eh-item     \"  data-item-class=\"eltdf-eh-custom-9445\" data-1366-1600=\"148px 45px 25px 45px\" data-1024-1366=\"148px 45px 25px 45px\" data-768-1024=\"148px 45px 25px 45px\" data-680-768=\"148px 0 50px 0\" data-680=\"148px 0 50px 0\">\n\t\t<div class=\"eltdf-eh-item-inner\">\n\t\t<div class=\"eltdf-eh-item-content eltdf-eh-custom-9445\" style=\"padding: 148px 0px 0 0\">\n\t\t\t<div class=\"eltdf-section-title-holder  eltdf-st-standard eltdf-st-title-left eltdf-st-normal-space \" >\n\t<div class=\"eltdf-st-inner\">\n\t\t\t\t\t<h1 class=\"eltdf-st-title\" >\n\t\t\t\tTalk to me\t\t\t<\/h1>\n\t\t\t\t\t\t\t<div class=\"eltdf-separator-holder clearfix   \">\n\t<div class=\"eltdf-separator\" style=\"margin-top: 13px;margin-bottom: -5px\"><\/div>\n<\/div>\n\t\t\t\t\t\t\t<p class=\"eltdf-st-text\" >\n\t\t\t\tLet's set up our first meeting to get started on your project. Let me know what your idea is, if you have a plot of land and where, what style do you like... I want to get to know you and your project!\t\t\t<\/p>\n\t\t\t<\/div>\n<\/div>[vc_empty_space height=\u00bb10px\u00bb][vc_raw_js]JTNDc2NyaXB0JTIwdHlwZSUzRCUyMnRleHQlMkZqYXZhc2NyaXB0JTIyJTIwc3JjJTNEJTIyaHR0cHMlM0ElMkYlMkZmb3JtLmpvdGZvcm0uY28lMkZqc2Zvcm0lMkY2MjUxNzYyMDM1NTg1NyUyMiUzRSUzQyUyRnNjcmlwdCUzRQ==[\/vc_raw_js]\t\t<\/div>\n\t<\/div>\n<\/div>\n\n<\/div>[\/vc_column][\/vc_row][vc_row content_placement=\u00bbtop\u00bb row_content_width=\u00bbgrid\u00bb css=\u00bb.vc_custom_1523962534372{padding-top: 115px !important;padding-bottom: 130px !important;}\u00bb][vc_column]<div class=\"eltdf-elements-holder   eltdf-four-columns  eltdf-responsive-mode-1024 \" ><div class=\"eltdf-eh-item  eltdf-vertical-alignment-top   \"  data-item-class=\"eltdf-eh-custom-7166\" data-1366-1600=\"0 0 0 40px\" data-1024-1366=\"0 0 0 0\" data-768-1024=\"0 0 50px 0\" data-680-768=\"0 0 50px 0\" data-680=\"0 0 50px 0\">\n\t\t<div class=\"eltdf-eh-item-inner\">\n\t\t<div class=\"eltdf-eh-item-content eltdf-eh-custom-7166\" style=\"padding: 0 0 0 0\">\n\t\t\t<div class=\"eltdf-single-image-holder   \">\n    <div class=\"eltdf-si-inner\" >\n                                    <img decoding=\"async\" width=\"600\" height=\"236\" data-src=\"https:\/\/espacio.co.cr\/rudinarquitectura\/en\/wp-content\/uploads\/2021\/03\/Rudin-logo-footer-negro-ingle\u0301s.png\" class=\"attachment-full size-full lazyload\" alt=\"Rudin Architects Costa Rica\" data-srcset=\"https:\/\/espacio.co.cr\/rudinarquitectura\/en\/wp-content\/uploads\/2021\/03\/Rudin-logo-footer-negro-ingle\u0301s.png 600w, https:\/\/espacio.co.cr\/rudinarquitectura\/en\/wp-content\/uploads\/2021\/03\/Rudin-logo-footer-negro-ingle\u0301s-300x118.png 300w\" data-sizes=\"(max-width: 600px) 100vw, 600px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 600px; --smush-placeholder-aspect-ratio: 600\/236;\" \/>                        <\/div>\n<\/div>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"eltdf-eh-item  eltdf-vertical-alignment-top   \"  data-item-class=\"eltdf-eh-custom-6354\" data-1366-1600=\"0px 0 32px 40px\" data-1024-1366=\"0px 0 32px 36px\" data-768-1024=\"0 0 50px 0\" data-680-768=\"0 0 50px 0\" data-680=\"0 0 50px 0\">\n\t\t<div class=\"eltdf-eh-item-inner\">\n\t\t<div class=\"eltdf-eh-item-content eltdf-eh-custom-6354\" style=\"padding: 0px 0 32px 19px\">\n\t\t\t[vc_column_text]We design soulful spaces! Our architecture reacts to the characteristics of the site and the wants and needs of our clients. Let&#8217;s talk and start to make your ideas happen![\/vc_column_text]\t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"eltdf-eh-item  eltdf-vertical-alignment-top eltdf-horizontal-alignment-right  \"  data-item-class=\"eltdf-eh-custom-9864\" data-1366-1600=\"0 65px 0 40px\" data-1024-1366=\"0 65px 0 27px\" data-768-1024=\"0 0 50px 0\" data-680-768=\"0 0 50px 0\" data-680=\"0 0 50px 0\">\n\t\t<div class=\"eltdf-eh-item-inner\">\n\t\t<div class=\"eltdf-eh-item-content eltdf-eh-custom-9864\" style=\"padding: 0 65px 0 27px\">\n\t\t\t[vc_column_text]<span style=\"font-size: 22px;\">Costa Rica,<\/span><\/p>\n<p><span style=\"font-size: 22px;\">all around!<\/span>[\/vc_column_text][vc_empty_space height=\u00bb10px\u00bb]<div class=\"eltdf-iwt clearfix eltdf-iwt-icon-font  eltdf-iwt-icon-left eltdf-iwt-icon-medium\">\n\t<div class=\"eltdf-iwt-icon\">\n\t\t\t\t\t<a itemprop=\"url\" href=\"#\" target=\"_self\">\n\t\t\t\t\t\t\t\t\t    <span class=\"eltdf-icon-shortcode eltdf-normal   eltdf-icon-medium\"  data-hover-color=\"#ee9445\" data-color=\"#000000\">\n                    <span aria-hidden=\"true\" class=\"eltdf-icon-font-elegant icon_phone eltdf-icon-element\" style=\"color: #000000;font-size:15px\" ><\/span>            <\/span>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t<div class=\"eltdf-iwt-content\" >\n\t\t\t\t\t\t\t<p class=\"eltdf-iwt-text\" style=\"margin-top: 4px\">+506 8841 6181<\/p>\n\t\t\t<\/div>\n\t<\/div>[vc_empty_space height=\u00bb4px\u00bb]<div class=\"eltdf-iwt clearfix eltdf-iwt-icon-font  eltdf-iwt-icon-left eltdf-iwt-icon-medium\">\n\t<div class=\"eltdf-iwt-icon\">\n\t\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/www.facebook.com\/arquitecturaconalma\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t\t\t    <span class=\"eltdf-icon-shortcode eltdf-normal   eltdf-icon-medium\"  data-hover-color=\"#ee9445\" data-color=\"#000000\">\n                    <span aria-hidden=\"true\" class=\"eltdf-icon-font-elegant social_facebook eltdf-icon-element\" style=\"color: #000000;font-size:15px\" ><\/span>            <\/span>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t<div class=\"eltdf-iwt-content\" >\n\t\t\t\t\t\t\t<p class=\"eltdf-iwt-text\" style=\"margin-top: 4px\">Rudin Arquitectura<\/p>\n\t\t\t<\/div>\n\t<\/div>[vc_empty_space height=\u00bb4px\u00bb]<div class=\"eltdf-iwt clearfix eltdf-iwt-icon-font  eltdf-iwt-icon-left eltdf-iwt-icon-medium\">\n\t<div class=\"eltdf-iwt-icon\">\n\t\t\t\t\t<a itemprop=\"url\" href=\"mailto:%20melissa@rudinarquitectura.com\" target=\"_self\">\n\t\t\t\t\t\t\t\t\t    <span class=\"eltdf-icon-shortcode eltdf-normal   eltdf-icon-medium\"  data-hover-color=\"#ee9445\" data-color=\"#000000\">\n                    <span aria-hidden=\"true\" class=\"eltdf-icon-font-elegant icon_mail_alt eltdf-icon-element\" style=\"color: #000000;font-size:15px\" ><\/span>            <\/span>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t<div class=\"eltdf-iwt-content\" >\n\t\t\t\t\t\t\t<p class=\"eltdf-iwt-text\" style=\"margin-top: 4px\">melissa@rudinarquitectura.com<\/p>\n\t\t\t<\/div>\n\t<\/div>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"eltdf-eh-item  eltdf-vertical-alignment-top   \"  data-item-class=\"eltdf-eh-custom-6086\" data-1366-1600=\"0 0 0 0\" data-1024-1366=\"0 0 0 25px\" data-768-1024=\"0 0 50px 0\" data-680-768=\"0 0 50px 0\" data-680=\"0 0 50px 0\">\n\t\t<div class=\"eltdf-eh-item-inner\">\n\t\t<div class=\"eltdf-eh-item-content eltdf-eh-custom-6086\" style=\"padding: 0 0 0 19px\">\n\t\t\t[vc_column_text]<span style=\"font-size: 22px; font-weight: 300;\">Espacio <\/span><\/p>\n<p><span style=\"font-size: 22px; font-weight: 300;\">Architecture blog (in spanish)<\/span>[\/vc_column_text][vc_empty_space height=\u00bb5px\u00bb]<div class=\"eltdf-iwt clearfix eltdf-iwt-icon-font  eltdf-iwt-icon-left eltdf-iwt-icon-medium\">\n\t<div class=\"eltdf-iwt-icon\">\n\t\t\t\t\t<a itemprop=\"url\" href=\"http:\/\/espacio.co.cr\/\" target=\"_blank\">\n\t\t\t\t\t\t\t\t\t    <span class=\"eltdf-icon-shortcode eltdf-normal   eltdf-icon-medium\"  data-hover-color=\"#ee9445\" data-color=\"#000000\">\n                    <i class=\"eltdf-icon-font-awesome fa fa-globe eltdf-icon-element\" style=\"color: #000000;font-size:15px\" ><\/i>            <\/span>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t<div class=\"eltdf-iwt-content\" >\n\t\t\t\t\t\t\t<p class=\"eltdf-iwt-text\" style=\"margin-top: 4px\">www.espacio.co.cr<\/p>\n\t\t\t<\/div>\n\t<\/div>[vc_empty_space height=\u00bb4px\u00bb]<div class=\"eltdf-iwt clearfix eltdf-iwt-icon-font  eltdf-iwt-icon-left eltdf-iwt-icon-medium\">\n\t<div class=\"eltdf-iwt-icon\">\n\t\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/www.facebook.com\/espacioarquitecturablog\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t\t\t    <span class=\"eltdf-icon-shortcode eltdf-normal   eltdf-icon-medium\"  data-hover-color=\"#ee9445\" data-color=\"#000000\">\n                    <span aria-hidden=\"true\" class=\"eltdf-icon-font-elegant social_facebook eltdf-icon-element\" style=\"color: #000000;font-size:15px\" ><\/span>            <\/span>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t<div class=\"eltdf-iwt-content\" >\n\t\t\t\t\t\t\t<p class=\"eltdf-iwt-text\" style=\"margin-top: 4px\">Espacio - blog de arquitectura<\/p>\n\t\t\t<\/div>\n\t<\/div>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n<\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=\u00bb.vc_custom_1525773762316{padding-top: 0px !important;}\u00bb parallax_background_image=\u00bb4338&#8243;][vc_column][\/vc_column][\/vc_row][vc_row equal_height=\u00bbyes\u00bb row_content_width=\u00bbgrid\u00bb disable_background_image=\u00bb\u00bb simple_background_image=\u00bb528&#8243; css=\u00bb.vc_custom_1591904707006{padding-right: 0px !important;padding-bottom: 133px !important;padding-left: 0px !important;}\u00bb][vc_column][\/vc_column][\/vc_row][vc_row content_placement=\u00bbtop\u00bb row_content_width=\u00bbgrid\u00bb css=\u00bb.vc_custom_1523962534372{padding-top: 115px !important;padding-bottom: 130px !important;}\u00bb][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-698","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/espacio.co.cr\/rudinarquitectura\/en\/wp-json\/wp\/v2\/pages\/698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacio.co.cr\/rudinarquitectura\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/espacio.co.cr\/rudinarquitectura\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/espacio.co.cr\/rudinarquitectura\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/espacio.co.cr\/rudinarquitectura\/en\/wp-json\/wp\/v2\/comments?post=698"}],"version-history":[{"count":68,"href":"https:\/\/espacio.co.cr\/rudinarquitectura\/en\/wp-json\/wp\/v2\/pages\/698\/revisions"}],"predecessor-version":[{"id":10760,"href":"https:\/\/espacio.co.cr\/rudinarquitectura\/en\/wp-json\/wp\/v2\/pages\/698\/revisions\/10760"}],"wp:attachment":[{"href":"https:\/\/espacio.co.cr\/rudinarquitectura\/en\/wp-json\/wp\/v2\/media?parent=698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}